{"id":39187,"date":"2022-08-12T13:30:24","date_gmt":"2022-08-12T11:30:24","guid":{"rendered":"https:\/\/www.elvendrellturistic.com\/los-jardines-del-albergue-de-coma-ruga-acogen-un-festival-de-circo\/"},"modified":"2022-08-18T17:02:11","modified_gmt":"2022-08-18T15:02:11","slug":"los-jardines-del-albergue-de-coma-ruga-acogen-un-festival-de-circo","status":"publish","type":"post","link":"https:\/\/www.elvendrellturisme.com\/es\/los-jardines-del-albergue-de-coma-ruga-acogen-un-festival-de-circo\/","title":{"rendered":"Los jardines del Albergue de Coma-ruga acogen un festival de circo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Del 18 al 21 de agosto, desde las 7 de la tarde hasta la medianoche, los jardines del Albergue de Coma-ruga, entre la avenida Palfuriana y el paseo Mar\u00edtim, acoger\u00e1n el 1er Festival Circus Parade.<\/p>\n\n<p class=\"wp-block-paragraph\">Se trata de un festival de circo promovido por un grupo de artistas que, a trav\u00e9s del juego y la diversi\u00f3n, quiere incidir en distintos temas de actualidad, como puede ser la preservaci\u00f3n del medio ambiente. Se presenta en un formato de parque de atracciones a la antigua y, con precios muy populares, los visitantes podr\u00e1n jugar, divertirse y ver espect\u00e1culos de peque\u00f1o formato, tanto magia como payasos. Las actividades est\u00e1n dirigidas a todo tipo de p\u00fablico, pero est\u00e1n muy pensadas para participar en familia.<\/p>\n\n<p class=\"wp-block-paragraph\">Cada d\u00eda, antes de empezar la actividad, a las 18.30 h se iniciar\u00e1 un pasacalle desde la zona del lago de Coma-ruga que recorrer\u00e1 la plaza Germans Trillas y el paseo Mar\u00edtimo hasta llegar a los jardines del Albergue .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 18 al 21 de agosto, desde las 7 de la tarde hasta la medianoche, los jardines del Albergue de Coma-ruga, entre la avenida Palfuriana y el paseo Mar\u00edtim, acoger\u00e1n el 1er Festival Circus Parade. Se trata de un festival de circo promovido por un grupo de artistas que, a trav\u00e9s del juego y la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39184,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","footnotes":""},"categories":[112],"tags":[],"dipi_cpt_category":[],"class_list":["post-39187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/posts\/39187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/comments?post=39187"}],"version-history":[{"count":2,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/posts\/39187\/revisions"}],"predecessor-version":[{"id":39208,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/posts\/39187\/revisions\/39208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/media\/39184"}],"wp:attachment":[{"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/media?parent=39187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/categories?post=39187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/tags?post=39187"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/www.elvendrellturisme.com\/es\/wp-json\/wp\/v2\/dipi_cpt_category?post=39187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}